{"id":797,"date":"2019-06-05T11:02:27","date_gmt":"2019-06-05T11:02:27","guid":{"rendered":"http:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01.jpg"},"modified":"2020-09-02T10:24:23","modified_gmt":"2020-09-02T10:24:23","slug":"lehrheft_zig-green_digital_seite_01","status":"inherit","type":"attachment","link":"https:\/\/www.systeme-d.org\/en\/projects\/zig-green\/lehrheft_zig-green_digital_seite_01\/","title":{"rendered":""},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-797","attachment","type-attachment","status-inherit","hentry"],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"en","enabled_languages":["de","en","fr"],"languages":{"de":{"title":false},"en":{"title":false},"fr":{"title":false}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01-212x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01-212x300.jpg 212w, https:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01-768x1086.jpg 768w, https:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01-724x1024.jpg 724w, https:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01-500x707.jpg 500w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":3283,"height":4643,"file":"2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01.jpg","sizes":{"thumbnail":{"file":"Lehrheft_ZIG-GREEN_digital_Seite_01-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01-150x150.jpg"},"medium":{"file":"Lehrheft_ZIG-GREEN_digital_Seite_01-212x300.jpg","width":212,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01-212x300.jpg"},"medium_large":{"file":"Lehrheft_ZIG-GREEN_digital_Seite_01-768x1086.jpg","width":768,"height":1086,"mime_type":"image\/jpeg","source_url":"https:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01-768x1086.jpg"},"large":{"file":"Lehrheft_ZIG-GREEN_digital_Seite_01-724x1024.jpg","width":724,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01-724x1024.jpg"},"carbon_logo":{"file":"Lehrheft_ZIG-GREEN_digital_Seite_01-500x707.jpg","width":500,"height":707,"mime_type":"image\/jpeg","source_url":"https:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01-500x707.jpg"},"full":{"file":"Lehrheft_ZIG-GREEN_digital_Seite_01.jpg","width":3283,"height":4643,"mime_type":"image\/jpeg","source_url":"https:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":482,"source_url":"https:\/\/www.systeme-d.org\/wp-content\/uploads\/2019\/06\/Lehrheft_ZIG-GREEN_digital_Seite_01.jpg","filename":"Lehrheft_ZIG-GREEN_digital_Seite_01.jpg","filesize":899059,"_links":{"self":[{"href":"https:\/\/www.systeme-d.org\/en\/wp-json\/wp\/v2\/media\/797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.systeme-d.org\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.systeme-d.org\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.systeme-d.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.systeme-d.org\/en\/wp-json\/wp\/v2\/comments?post=797"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":482,"href":"https:\/\/www.systeme-d.org\/en\/wp-json\/wp\/v2\/pages\/482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}